{"id":9309,"date":"2026-02-02T16:01:52","date_gmt":"2026-02-02T15:01:52","guid":{"rendered":"https:\/\/www.eurosets.com\/?page_id=9309"},"modified":"2026-06-23T12:14:02","modified_gmt":"2026-06-23T10:14:02","slug":"documentation","status":"publish","type":"page","link":"https:\/\/www.eurosets.com\/it\/documentation\/","title":{"rendered":"Documentazione"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9309\" class=\"elementor elementor-9309\" data-elementor-post-type=\"page\">\n\t\t\t\t<div data-dce-background-color=\"#F3F5F8\" data-dce-background-overlay-color=\"#003D6B\" data-dce-background-image-url=\"https:\/\/www.eurosets.com\/wp-content\/uploads\/2023\/09\/homepage_no_video.jpg\" class=\"elementor-element elementor-element-da37f35 animated-slow e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"da37f35\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;animation&quot;:&quot;fadeInDown&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div data-dce-title-color=\"#FFFFFF\" class=\"elementor-element elementor-element-937cf04 elementor-widget elementor-widget-heading\" data-id=\"937cf04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><b>DOCUMENTATION<\/b><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-title-color=\"#FFFFFF\" class=\"elementor-element elementor-element-668bdf5 elementor-widget elementor-widget-heading\" data-id=\"668bdf5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Welcome to the Eurosets Documentation area. We are committed to supporting healthcare professionals by providing easy access to the latest technical and clinical information regarding our life-saving portfolio.<\/h5>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bf67f0a e-flex e-con-boxed e-con e-parent\" data-id=\"bf67f0a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9bfe043 dce-posts-layout-template elementor-widget__width-inherit lista_documenti dce-col-4 dce-col-tablet-3 dce-col-mobile-1 elementor-widget elementor-widget-dce-dynamicposts-v2\" data-id=\"9bfe043\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;style_items&quot;:&quot;template&quot;,&quot;grid_match_height&quot;:&quot;yes&quot;,&quot;grid_match_height_by_row&quot;:&quot;true&quot;,&quot;grid_grid_type&quot;:&quot;flex&quot;}\" data-widget_type=\"dce-dynamicposts-v2.grid\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"dce-fix-background-loop dce-posts-container dce-posts dce-dynamic-posts-collection reveal-effect reveal-effect-1 dce-skin-grid dce-skin-grid-flex\">\n\t\t\t\t\t\t<div class=\"dce-posts-wrapper dce-wrapper-grid\">\n\t\t\t\n\t\t<article class=\"post-9306 certification type-certification status-publish hentry certification-category-documentation dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"9306\" data-dce-post-index=\"0\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<style id=\"loop-9323\">.elementor-9323 .elementor-element.elementor-element-ef506d7{--display:flex;--flex-direction:column;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:flex-start;--align-items:center;--background-transition:0.3s;--border-radius:20px 20px 20px 20px;--margin-top:10px;--margin-bottom:10px;--margin-left:10px;--margin-right:10px;--padding-top:20px;--padding-bottom:20px;--padding-left:20px;--padding-right:20px;}.elementor-9323 .elementor-element.elementor-element-ef506d7:not(.elementor-motion-effects-element-type-background), .elementor-9323 .elementor-element.elementor-element-ef506d7 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#63AADC17;}.elementor-9323 .elementor-element.elementor-element-ef506d7:hover{background-color:#63AADC30;}.elementor-9323 .elementor-element.elementor-element-affdc25 .elementor-icon-wrapper{text-align:center;}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-stacked .elementor-icon{background-color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-framed .elementor-icon, .elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-default .elementor-icon{color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-framed .elementor-icon, .elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-default .elementor-icon svg{fill:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-b217cb3{text-align:center;margin:05px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;}.elementor-9323 .elementor-element.elementor-element-b217cb3 .elementor-heading-title{font-family:\"Rubik\", Sans-serif;font-size:16px;font-weight:bold;text-transform:uppercase;line-height:1em;color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-c39e954{text-align:center;color:var( --e-global-color-text );font-family:\"Rubik\", Sans-serif;font-size:14px;font-weight:300;line-height:1.2em;margin:5px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;}.elementor-9323 .elementor-element.elementor-element-7143336{text-align:center;font-size:14px;}@media(max-width:1024px){.elementor-9323 .elementor-element.elementor-element-c39e954{line-height:1.5em;}}@media(min-width:768px){.elementor-9323 .elementor-element.elementor-element-ef506d7{--content-width:100%;}}@media(max-width:767px){.elementor-9323 .elementor-element.elementor-element-c39e954{font-size:16px;line-height:1.3em;}}\/* Start custom CSS for container, class: .elementor-element-ef506d7 *\/.elementor-9323 .elementor-element.elementor-element-ef506d7{\n    max-width: 400px;\n}\/* End custom CSS *\/<\/style><style>.elementor-9323 .elementor-element.elementor-element-ef506d7{--display:flex;--flex-direction:column;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:flex-start;--align-items:center;--background-transition:0.3s;--border-radius:20px 20px 20px 20px;--margin-top:10px;--margin-bottom:10px;--margin-left:10px;--margin-right:10px;--padding-top:20px;--padding-bottom:20px;--padding-left:20px;--padding-right:20px;}.elementor-9323 .elementor-element.elementor-element-ef506d7:not(.elementor-motion-effects-element-type-background), .elementor-9323 .elementor-element.elementor-element-ef506d7 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#63AADC17;}.elementor-9323 .elementor-element.elementor-element-ef506d7:hover{background-color:#63AADC30;}.elementor-9323 .elementor-element.elementor-element-affdc25 .elementor-icon-wrapper{text-align:center;}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-stacked .elementor-icon{background-color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-framed .elementor-icon, .elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-default .elementor-icon{color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-framed .elementor-icon, .elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-default .elementor-icon svg{fill:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-b217cb3{text-align:center;margin:05px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;}.elementor-9323 .elementor-element.elementor-element-b217cb3 .elementor-heading-title{font-family:\"Rubik\", Sans-serif;font-size:16px;font-weight:bold;text-transform:uppercase;line-height:1em;color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-c39e954{text-align:center;color:var( --e-global-color-text );font-family:\"Rubik\", Sans-serif;font-size:14px;font-weight:300;line-height:1.2em;margin:5px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;}.elementor-9323 .elementor-element.elementor-element-7143336{text-align:center;font-size:14px;}@media(max-width:1024px){.elementor-9323 .elementor-element.elementor-element-c39e954{line-height:1.5em;}}@media(min-width:768px){.elementor-9323 .elementor-element.elementor-element-ef506d7{--content-width:100%;}}@media(max-width:767px){.elementor-9323 .elementor-element.elementor-element-c39e954{font-size:16px;line-height:1.3em;}}\/* Start custom CSS for container, class: .elementor-element-ef506d7 *\/.elementor-9323 .elementor-element.elementor-element-ef506d7{\n    max-width: 400px;\n}\/* End custom CSS *\/<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"9323\" class=\"elementor elementor-9323 dce-elementor-rendering-id-1 e-loop-item e-loop-item-9306 post-9306 certification type-certification status-publish hentry certification-category-documentation\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a data-dce-background-color=\"#63AADC17\" data-dce-background-hover-color=\"#63AADC30\" class=\"elementor-element elementor-element-ef506d7 e-flex e-con-boxed e-con e-parent\" data-id=\"ef506d7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/www.eurosets.com\/wp-content\/uploads\/2026\/02\/Policy-antibribery-EUROSETS.pdf\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-affdc25 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"affdc25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-file-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288 248v28c0 6.6-5.4 12-12 12H108c-6.6 0-12-5.4-12-12v-28c0-6.6 5.4-12 12-12h168c6.6 0 12 5.4 12 12zm-12 72H108c-6.6 0-12 5.4-12 12v28c0 6.6 5.4 12 12 12h168c6.6 0 12-5.4 12-12v-28c0-6.6-5.4-12-12-12zm108-188.1V464c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V48C0 21.5 21.5 0 48 0h204.1C264.8 0 277 5.1 286 14.1L369.9 98c9 8.9 14.1 21.2 14.1 33.9zm-128-80V128h76.1L256 51.9zM336 464V176H232c-13.3 0-24-10.7-24-24V48H48v416h288z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-title-color=\"#003D6B\" class=\"elementor-element elementor-element-b217cb3 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"b217cb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Anti-bribery Policy<\/h4>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-9363 certification type-certification status-publish hentry certification-category-documentation dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"9363\" data-dce-post-index=\"1\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<style>.elementor-9323 .elementor-element.elementor-element-ef506d7{--display:flex;--flex-direction:column;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:flex-start;--align-items:center;--background-transition:0.3s;--border-radius:20px 20px 20px 20px;--margin-top:10px;--margin-bottom:10px;--margin-left:10px;--margin-right:10px;--padding-top:20px;--padding-bottom:20px;--padding-left:20px;--padding-right:20px;}.elementor-9323 .elementor-element.elementor-element-ef506d7:not(.elementor-motion-effects-element-type-background), .elementor-9323 .elementor-element.elementor-element-ef506d7 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#63AADC17;}.elementor-9323 .elementor-element.elementor-element-ef506d7:hover{background-color:#63AADC30;}.elementor-9323 .elementor-element.elementor-element-affdc25 .elementor-icon-wrapper{text-align:center;}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-stacked .elementor-icon{background-color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-framed .elementor-icon, .elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-default .elementor-icon{color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-framed .elementor-icon, .elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-default .elementor-icon svg{fill:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-b217cb3{text-align:center;margin:05px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;}.elementor-9323 .elementor-element.elementor-element-b217cb3 .elementor-heading-title{font-family:\"Rubik\", Sans-serif;font-size:16px;font-weight:bold;text-transform:uppercase;line-height:1em;color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-c39e954{text-align:center;color:var( --e-global-color-text );font-family:\"Rubik\", Sans-serif;font-size:14px;font-weight:300;line-height:1.2em;margin:5px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;}.elementor-9323 .elementor-element.elementor-element-7143336{text-align:center;font-size:14px;}@media(max-width:1024px){.elementor-9323 .elementor-element.elementor-element-c39e954{line-height:1.5em;}}@media(min-width:768px){.elementor-9323 .elementor-element.elementor-element-ef506d7{--content-width:100%;}}@media(max-width:767px){.elementor-9323 .elementor-element.elementor-element-c39e954{font-size:16px;line-height:1.3em;}}\/* Start custom CSS for container, class: .elementor-element-ef506d7 *\/.elementor-9323 .elementor-element.elementor-element-ef506d7{\n    max-width: 400px;\n}\/* End custom CSS *\/<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"9323\" class=\"elementor elementor-9323 dce-elementor-rendering-id-2 e-loop-item e-loop-item-9363 post-9363 certification type-certification status-publish hentry certification-category-documentation\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a data-dce-background-color=\"#63AADC17\" data-dce-background-hover-color=\"#63AADC30\" class=\"elementor-element elementor-element-ef506d7 e-flex e-con-boxed e-con e-parent\" data-id=\"ef506d7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/www.eurosets.com\/wp-content\/uploads\/2026\/02\/Politica-Anti-Harassment_REV_001.pdf\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-affdc25 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"affdc25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-file-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288 248v28c0 6.6-5.4 12-12 12H108c-6.6 0-12-5.4-12-12v-28c0-6.6 5.4-12 12-12h168c6.6 0 12 5.4 12 12zm-12 72H108c-6.6 0-12 5.4-12 12v28c0 6.6 5.4 12 12 12h168c6.6 0 12-5.4 12-12v-28c0-6.6-5.4-12-12-12zm108-188.1V464c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V48C0 21.5 21.5 0 48 0h204.1C264.8 0 277 5.1 286 14.1L369.9 98c9 8.9 14.1 21.2 14.1 33.9zm-128-80V128h76.1L256 51.9zM336 464V176H232c-13.3 0-24-10.7-24-24V48H48v416h288z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-title-color=\"#003D6B\" class=\"elementor-element elementor-element-b217cb3 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"b217cb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Anti-Harassment Policy<\/h4>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-9496 certification type-certification status-publish hentry certification-category-documentation dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"9496\" data-dce-post-index=\"2\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<style>.elementor-9323 .elementor-element.elementor-element-ef506d7{--display:flex;--flex-direction:column;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:flex-start;--align-items:center;--background-transition:0.3s;--border-radius:20px 20px 20px 20px;--margin-top:10px;--margin-bottom:10px;--margin-left:10px;--margin-right:10px;--padding-top:20px;--padding-bottom:20px;--padding-left:20px;--padding-right:20px;}.elementor-9323 .elementor-element.elementor-element-ef506d7:not(.elementor-motion-effects-element-type-background), .elementor-9323 .elementor-element.elementor-element-ef506d7 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#63AADC17;}.elementor-9323 .elementor-element.elementor-element-ef506d7:hover{background-color:#63AADC30;}.elementor-9323 .elementor-element.elementor-element-affdc25 .elementor-icon-wrapper{text-align:center;}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-stacked .elementor-icon{background-color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-framed .elementor-icon, .elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-default .elementor-icon{color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-framed .elementor-icon, .elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-default .elementor-icon svg{fill:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-b217cb3{text-align:center;margin:05px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;}.elementor-9323 .elementor-element.elementor-element-b217cb3 .elementor-heading-title{font-family:\"Rubik\", Sans-serif;font-size:16px;font-weight:bold;text-transform:uppercase;line-height:1em;color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-c39e954{text-align:center;color:var( --e-global-color-text );font-family:\"Rubik\", Sans-serif;font-size:14px;font-weight:300;line-height:1.2em;margin:5px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;}.elementor-9323 .elementor-element.elementor-element-7143336{text-align:center;font-size:14px;}@media(max-width:1024px){.elementor-9323 .elementor-element.elementor-element-c39e954{line-height:1.5em;}}@media(min-width:768px){.elementor-9323 .elementor-element.elementor-element-ef506d7{--content-width:100%;}}@media(max-width:767px){.elementor-9323 .elementor-element.elementor-element-c39e954{font-size:16px;line-height:1.3em;}}\/* Start custom CSS for container, class: .elementor-element-ef506d7 *\/.elementor-9323 .elementor-element.elementor-element-ef506d7{\n    max-width: 400px;\n}\/* End custom CSS *\/<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"9323\" class=\"elementor elementor-9323 dce-elementor-rendering-id-3 e-loop-item e-loop-item-9496 post-9496 certification type-certification status-publish hentry certification-category-documentation\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a data-dce-background-color=\"#63AADC17\" data-dce-background-hover-color=\"#63AADC30\" class=\"elementor-element elementor-element-ef506d7 e-flex e-con-boxed e-con e-parent\" data-id=\"ef506d7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/www.eurosets.com\/wp-content\/uploads\/2026\/02\/Eurosets-UK-Limited-Carbon-Reduction-Plan-2025-web-version.pdf\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-affdc25 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"affdc25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-file-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288 248v28c0 6.6-5.4 12-12 12H108c-6.6 0-12-5.4-12-12v-28c0-6.6 5.4-12 12-12h168c6.6 0 12 5.4 12 12zm-12 72H108c-6.6 0-12 5.4-12 12v28c0 6.6 5.4 12 12 12h168c6.6 0 12-5.4 12-12v-28c0-6.6-5.4-12-12-12zm108-188.1V464c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V48C0 21.5 21.5 0 48 0h204.1C264.8 0 277 5.1 286 14.1L369.9 98c9 8.9 14.1 21.2 14.1 33.9zm-128-80V128h76.1L256 51.9zM336 464V176H232c-13.3 0-24-10.7-24-24V48H48v416h288z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-title-color=\"#003D6B\" class=\"elementor-element elementor-element-b217cb3 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"b217cb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Carbon Reduction Plan<\/h4>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-9346 certification type-certification status-publish hentry certification-category-documentation dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"9346\" data-dce-post-index=\"3\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<style>.elementor-9323 .elementor-element.elementor-element-ef506d7{--display:flex;--flex-direction:column;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:flex-start;--align-items:center;--background-transition:0.3s;--border-radius:20px 20px 20px 20px;--margin-top:10px;--margin-bottom:10px;--margin-left:10px;--margin-right:10px;--padding-top:20px;--padding-bottom:20px;--padding-left:20px;--padding-right:20px;}.elementor-9323 .elementor-element.elementor-element-ef506d7:not(.elementor-motion-effects-element-type-background), .elementor-9323 .elementor-element.elementor-element-ef506d7 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#63AADC17;}.elementor-9323 .elementor-element.elementor-element-ef506d7:hover{background-color:#63AADC30;}.elementor-9323 .elementor-element.elementor-element-affdc25 .elementor-icon-wrapper{text-align:center;}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-stacked .elementor-icon{background-color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-framed .elementor-icon, .elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-default .elementor-icon{color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-framed .elementor-icon, .elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-default .elementor-icon svg{fill:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-b217cb3{text-align:center;margin:05px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;}.elementor-9323 .elementor-element.elementor-element-b217cb3 .elementor-heading-title{font-family:\"Rubik\", Sans-serif;font-size:16px;font-weight:bold;text-transform:uppercase;line-height:1em;color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-c39e954{text-align:center;color:var( --e-global-color-text );font-family:\"Rubik\", Sans-serif;font-size:14px;font-weight:300;line-height:1.2em;margin:5px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;}.elementor-9323 .elementor-element.elementor-element-7143336{text-align:center;font-size:14px;}@media(max-width:1024px){.elementor-9323 .elementor-element.elementor-element-c39e954{line-height:1.5em;}}@media(min-width:768px){.elementor-9323 .elementor-element.elementor-element-ef506d7{--content-width:100%;}}@media(max-width:767px){.elementor-9323 .elementor-element.elementor-element-c39e954{font-size:16px;line-height:1.3em;}}\/* Start custom CSS for container, class: .elementor-element-ef506d7 *\/.elementor-9323 .elementor-element.elementor-element-ef506d7{\n    max-width: 400px;\n}\/* End custom CSS *\/<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"9323\" class=\"elementor elementor-9323 dce-elementor-rendering-id-4 e-loop-item e-loop-item-9346 post-9346 certification type-certification status-publish hentry certification-category-documentation\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a data-dce-background-color=\"#63AADC17\" data-dce-background-hover-color=\"#63AADC30\" class=\"elementor-element elementor-element-ef506d7 e-flex e-con-boxed e-con e-parent\" data-id=\"ef506d7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/www.eurosets.com\/wp-content\/uploads\/2026\/02\/CODE-OF-ETHICS.pdf\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-affdc25 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"affdc25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-file-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288 248v28c0 6.6-5.4 12-12 12H108c-6.6 0-12-5.4-12-12v-28c0-6.6 5.4-12 12-12h168c6.6 0 12 5.4 12 12zm-12 72H108c-6.6 0-12 5.4-12 12v28c0 6.6 5.4 12 12 12h168c6.6 0 12-5.4 12-12v-28c0-6.6-5.4-12-12-12zm108-188.1V464c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V48C0 21.5 21.5 0 48 0h204.1C264.8 0 277 5.1 286 14.1L369.9 98c9 8.9 14.1 21.2 14.1 33.9zm-128-80V128h76.1L256 51.9zM336 464V176H232c-13.3 0-24-10.7-24-24V48H48v416h288z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-title-color=\"#003D6B\" class=\"elementor-element elementor-element-b217cb3 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"b217cb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Code Of Ethics<\/h4>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-9350 certification type-certification status-publish hentry certification-category-documentation dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"9350\" data-dce-post-index=\"4\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<style>.elementor-9323 .elementor-element.elementor-element-ef506d7{--display:flex;--flex-direction:column;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:flex-start;--align-items:center;--background-transition:0.3s;--border-radius:20px 20px 20px 20px;--margin-top:10px;--margin-bottom:10px;--margin-left:10px;--margin-right:10px;--padding-top:20px;--padding-bottom:20px;--padding-left:20px;--padding-right:20px;}.elementor-9323 .elementor-element.elementor-element-ef506d7:not(.elementor-motion-effects-element-type-background), .elementor-9323 .elementor-element.elementor-element-ef506d7 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#63AADC17;}.elementor-9323 .elementor-element.elementor-element-ef506d7:hover{background-color:#63AADC30;}.elementor-9323 .elementor-element.elementor-element-affdc25 .elementor-icon-wrapper{text-align:center;}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-stacked .elementor-icon{background-color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-framed .elementor-icon, .elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-default .elementor-icon{color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-framed .elementor-icon, .elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-default .elementor-icon svg{fill:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-b217cb3{text-align:center;margin:05px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;}.elementor-9323 .elementor-element.elementor-element-b217cb3 .elementor-heading-title{font-family:\"Rubik\", Sans-serif;font-size:16px;font-weight:bold;text-transform:uppercase;line-height:1em;color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-c39e954{text-align:center;color:var( --e-global-color-text );font-family:\"Rubik\", Sans-serif;font-size:14px;font-weight:300;line-height:1.2em;margin:5px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;}.elementor-9323 .elementor-element.elementor-element-7143336{text-align:center;font-size:14px;}@media(max-width:1024px){.elementor-9323 .elementor-element.elementor-element-c39e954{line-height:1.5em;}}@media(min-width:768px){.elementor-9323 .elementor-element.elementor-element-ef506d7{--content-width:100%;}}@media(max-width:767px){.elementor-9323 .elementor-element.elementor-element-c39e954{font-size:16px;line-height:1.3em;}}\/* Start custom CSS for container, class: .elementor-element-ef506d7 *\/.elementor-9323 .elementor-element.elementor-element-ef506d7{\n    max-width: 400px;\n}\/* End custom CSS *\/<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"9323\" class=\"elementor elementor-9323 dce-elementor-rendering-id-5 e-loop-item e-loop-item-9350 post-9350 certification type-certification status-publish hentry certification-category-documentation\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a data-dce-background-color=\"#63AADC17\" data-dce-background-hover-color=\"#63AADC30\" class=\"elementor-element elementor-element-ef506d7 e-flex e-con-boxed e-con e-parent\" data-id=\"ef506d7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/www.eurosets.com\/wp-content\/uploads\/2026\/06\/Environmental-and-Quality-Policy-rev.004_engl.pdf\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-affdc25 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"affdc25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-file-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288 248v28c0 6.6-5.4 12-12 12H108c-6.6 0-12-5.4-12-12v-28c0-6.6 5.4-12 12-12h168c6.6 0 12 5.4 12 12zm-12 72H108c-6.6 0-12 5.4-12 12v28c0 6.6 5.4 12 12 12h168c6.6 0 12-5.4 12-12v-28c0-6.6-5.4-12-12-12zm108-188.1V464c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V48C0 21.5 21.5 0 48 0h204.1C264.8 0 277 5.1 286 14.1L369.9 98c9 8.9 14.1 21.2 14.1 33.9zm-128-80V128h76.1L256 51.9zM336 464V176H232c-13.3 0-24-10.7-24-24V48H48v416h288z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-title-color=\"#003D6B\" class=\"elementor-element elementor-element-b217cb3 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"b217cb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Environmental &amp; Quality Policy<\/h4>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-9337 certification type-certification status-publish hentry dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"9337\" data-dce-post-index=\"5\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<style>.elementor-9323 .elementor-element.elementor-element-ef506d7{--display:flex;--flex-direction:column;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:flex-start;--align-items:center;--background-transition:0.3s;--border-radius:20px 20px 20px 20px;--margin-top:10px;--margin-bottom:10px;--margin-left:10px;--margin-right:10px;--padding-top:20px;--padding-bottom:20px;--padding-left:20px;--padding-right:20px;}.elementor-9323 .elementor-element.elementor-element-ef506d7:not(.elementor-motion-effects-element-type-background), .elementor-9323 .elementor-element.elementor-element-ef506d7 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#63AADC17;}.elementor-9323 .elementor-element.elementor-element-ef506d7:hover{background-color:#63AADC30;}.elementor-9323 .elementor-element.elementor-element-affdc25 .elementor-icon-wrapper{text-align:center;}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-stacked .elementor-icon{background-color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-framed .elementor-icon, .elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-default .elementor-icon{color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-framed .elementor-icon, .elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-default .elementor-icon svg{fill:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-b217cb3{text-align:center;margin:05px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;}.elementor-9323 .elementor-element.elementor-element-b217cb3 .elementor-heading-title{font-family:\"Rubik\", Sans-serif;font-size:16px;font-weight:bold;text-transform:uppercase;line-height:1em;color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-c39e954{text-align:center;color:var( --e-global-color-text );font-family:\"Rubik\", Sans-serif;font-size:14px;font-weight:300;line-height:1.2em;margin:5px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;}.elementor-9323 .elementor-element.elementor-element-7143336{text-align:center;font-size:14px;}@media(max-width:1024px){.elementor-9323 .elementor-element.elementor-element-c39e954{line-height:1.5em;}}@media(min-width:768px){.elementor-9323 .elementor-element.elementor-element-ef506d7{--content-width:100%;}}@media(max-width:767px){.elementor-9323 .elementor-element.elementor-element-c39e954{font-size:16px;line-height:1.3em;}}\/* Start custom CSS for container, class: .elementor-element-ef506d7 *\/.elementor-9323 .elementor-element.elementor-element-ef506d7{\n    max-width: 400px;\n}\/* End custom CSS *\/<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"9323\" class=\"elementor elementor-9323 dce-elementor-rendering-id-6 e-loop-item e-loop-item-9337 post-9337 certification type-certification status-publish hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a data-dce-background-color=\"#63AADC17\" data-dce-background-hover-color=\"#63AADC30\" class=\"elementor-element elementor-element-ef506d7 e-flex e-con-boxed e-con e-parent\" data-id=\"ef506d7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/www.eurosets.com\/wp-content\/uploads\/2026\/02\/EUROSETS-Libro-30-anni-ENG-1.pdf\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-affdc25 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"affdc25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-file-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288 248v28c0 6.6-5.4 12-12 12H108c-6.6 0-12-5.4-12-12v-28c0-6.6 5.4-12 12-12h168c6.6 0 12 5.4 12 12zm-12 72H108c-6.6 0-12 5.4-12 12v28c0 6.6 5.4 12 12 12h168c6.6 0 12-5.4 12-12v-28c0-6.6-5.4-12-12-12zm108-188.1V464c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V48C0 21.5 21.5 0 48 0h204.1C264.8 0 277 5.1 286 14.1L369.9 98c9 8.9 14.1 21.2 14.1 33.9zm-128-80V128h76.1L256 51.9zM336 464V176H232c-13.3 0-24-10.7-24-24V48H48v416h288z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-title-color=\"#003D6B\" class=\"elementor-element elementor-element-b217cb3 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"b217cb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Essence of Life<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c39e954 elementor-widget elementor-widget-theme-post-content\" data-id=\"c39e954\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-content.default\">\n\t\t\t\t\t\n<p class=\"wp-block-paragraph\">Eurosets&#8217; book for celebrating 30 years<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-9507 certification type-certification status-publish hentry certification-category-documentation dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"9507\" data-dce-post-index=\"6\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<style>.elementor-9323 .elementor-element.elementor-element-ef506d7{--display:flex;--flex-direction:column;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:flex-start;--align-items:center;--background-transition:0.3s;--border-radius:20px 20px 20px 20px;--margin-top:10px;--margin-bottom:10px;--margin-left:10px;--margin-right:10px;--padding-top:20px;--padding-bottom:20px;--padding-left:20px;--padding-right:20px;}.elementor-9323 .elementor-element.elementor-element-ef506d7:not(.elementor-motion-effects-element-type-background), .elementor-9323 .elementor-element.elementor-element-ef506d7 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#63AADC17;}.elementor-9323 .elementor-element.elementor-element-ef506d7:hover{background-color:#63AADC30;}.elementor-9323 .elementor-element.elementor-element-affdc25 .elementor-icon-wrapper{text-align:center;}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-stacked .elementor-icon{background-color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-framed .elementor-icon, .elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-default .elementor-icon{color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-framed .elementor-icon, .elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-default .elementor-icon svg{fill:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-b217cb3{text-align:center;margin:05px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;}.elementor-9323 .elementor-element.elementor-element-b217cb3 .elementor-heading-title{font-family:\"Rubik\", Sans-serif;font-size:16px;font-weight:bold;text-transform:uppercase;line-height:1em;color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-c39e954{text-align:center;color:var( --e-global-color-text );font-family:\"Rubik\", Sans-serif;font-size:14px;font-weight:300;line-height:1.2em;margin:5px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;}.elementor-9323 .elementor-element.elementor-element-7143336{text-align:center;font-size:14px;}@media(max-width:1024px){.elementor-9323 .elementor-element.elementor-element-c39e954{line-height:1.5em;}}@media(min-width:768px){.elementor-9323 .elementor-element.elementor-element-ef506d7{--content-width:100%;}}@media(max-width:767px){.elementor-9323 .elementor-element.elementor-element-c39e954{font-size:16px;line-height:1.3em;}}\/* Start custom CSS for container, class: .elementor-element-ef506d7 *\/.elementor-9323 .elementor-element.elementor-element-ef506d7{\n    max-width: 400px;\n}\/* End custom CSS *\/<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"9323\" class=\"elementor elementor-9323 dce-elementor-rendering-id-7 e-loop-item e-loop-item-9507 post-9507 certification type-certification status-publish hentry certification-category-documentation\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a data-dce-background-color=\"#63AADC17\" data-dce-background-hover-color=\"#63AADC30\" class=\"elementor-element elementor-element-ef506d7 e-flex e-con-boxed e-con e-parent\" data-id=\"ef506d7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/www.eurosets.com\/wp-content\/uploads\/2026\/02\/Modern-Slavery-Statement-V1.0.pdf\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-affdc25 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"affdc25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-file-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288 248v28c0 6.6-5.4 12-12 12H108c-6.6 0-12-5.4-12-12v-28c0-6.6 5.4-12 12-12h168c6.6 0 12 5.4 12 12zm-12 72H108c-6.6 0-12 5.4-12 12v28c0 6.6 5.4 12 12 12h168c6.6 0 12-5.4 12-12v-28c0-6.6-5.4-12-12-12zm108-188.1V464c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V48C0 21.5 21.5 0 48 0h204.1C264.8 0 277 5.1 286 14.1L369.9 98c9 8.9 14.1 21.2 14.1 33.9zm-128-80V128h76.1L256 51.9zM336 464V176H232c-13.3 0-24-10.7-24-24V48H48v416h288z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-title-color=\"#003D6B\" class=\"elementor-element elementor-element-b217cb3 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"b217cb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Modern Slavery Statement<\/h4>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-9348 certification type-certification status-publish hentry certification-category-documentation dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"9348\" data-dce-post-index=\"7\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<style>.elementor-9323 .elementor-element.elementor-element-ef506d7{--display:flex;--flex-direction:column;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:flex-start;--align-items:center;--background-transition:0.3s;--border-radius:20px 20px 20px 20px;--margin-top:10px;--margin-bottom:10px;--margin-left:10px;--margin-right:10px;--padding-top:20px;--padding-bottom:20px;--padding-left:20px;--padding-right:20px;}.elementor-9323 .elementor-element.elementor-element-ef506d7:not(.elementor-motion-effects-element-type-background), .elementor-9323 .elementor-element.elementor-element-ef506d7 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#63AADC17;}.elementor-9323 .elementor-element.elementor-element-ef506d7:hover{background-color:#63AADC30;}.elementor-9323 .elementor-element.elementor-element-affdc25 .elementor-icon-wrapper{text-align:center;}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-stacked .elementor-icon{background-color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-framed .elementor-icon, .elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-default .elementor-icon{color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-framed .elementor-icon, .elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-default .elementor-icon svg{fill:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-b217cb3{text-align:center;margin:05px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;}.elementor-9323 .elementor-element.elementor-element-b217cb3 .elementor-heading-title{font-family:\"Rubik\", Sans-serif;font-size:16px;font-weight:bold;text-transform:uppercase;line-height:1em;color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-c39e954{text-align:center;color:var( --e-global-color-text );font-family:\"Rubik\", Sans-serif;font-size:14px;font-weight:300;line-height:1.2em;margin:5px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;}.elementor-9323 .elementor-element.elementor-element-7143336{text-align:center;font-size:14px;}@media(max-width:1024px){.elementor-9323 .elementor-element.elementor-element-c39e954{line-height:1.5em;}}@media(min-width:768px){.elementor-9323 .elementor-element.elementor-element-ef506d7{--content-width:100%;}}@media(max-width:767px){.elementor-9323 .elementor-element.elementor-element-c39e954{font-size:16px;line-height:1.3em;}}\/* Start custom CSS for container, class: .elementor-element-ef506d7 *\/.elementor-9323 .elementor-element.elementor-element-ef506d7{\n    max-width: 400px;\n}\/* End custom CSS *\/<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"9323\" class=\"elementor elementor-9323 dce-elementor-rendering-id-8 e-loop-item e-loop-item-9348 post-9348 certification type-certification status-publish hentry certification-category-documentation\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a data-dce-background-color=\"#63AADC17\" data-dce-background-hover-color=\"#63AADC30\" class=\"elementor-element elementor-element-ef506d7 e-flex e-con-boxed e-con e-parent\" data-id=\"ef506d7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/www.eurosets.com\/wp-content\/uploads\/2026\/02\/Mog-231-Eurosets-p.generale-e-speciale-2024-EN.pdf\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-affdc25 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"affdc25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-file-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288 248v28c0 6.6-5.4 12-12 12H108c-6.6 0-12-5.4-12-12v-28c0-6.6 5.4-12 12-12h168c6.6 0 12 5.4 12 12zm-12 72H108c-6.6 0-12 5.4-12 12v28c0 6.6 5.4 12 12 12h168c6.6 0 12-5.4 12-12v-28c0-6.6-5.4-12-12-12zm108-188.1V464c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V48C0 21.5 21.5 0 48 0h204.1C264.8 0 277 5.1 286 14.1L369.9 98c9 8.9 14.1 21.2 14.1 33.9zm-128-80V128h76.1L256 51.9zM336 464V176H232c-13.3 0-24-10.7-24-24V48H48v416h288z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-title-color=\"#003D6B\" class=\"elementor-element elementor-element-b217cb3 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"b217cb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Mog 231<\/h4>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-9332 certification type-certification status-publish hentry certification-category-documentation dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"9332\" data-dce-post-index=\"8\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<style>.elementor-9323 .elementor-element.elementor-element-ef506d7{--display:flex;--flex-direction:column;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:flex-start;--align-items:center;--background-transition:0.3s;--border-radius:20px 20px 20px 20px;--margin-top:10px;--margin-bottom:10px;--margin-left:10px;--margin-right:10px;--padding-top:20px;--padding-bottom:20px;--padding-left:20px;--padding-right:20px;}.elementor-9323 .elementor-element.elementor-element-ef506d7:not(.elementor-motion-effects-element-type-background), .elementor-9323 .elementor-element.elementor-element-ef506d7 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#63AADC17;}.elementor-9323 .elementor-element.elementor-element-ef506d7:hover{background-color:#63AADC30;}.elementor-9323 .elementor-element.elementor-element-affdc25 .elementor-icon-wrapper{text-align:center;}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-stacked .elementor-icon{background-color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-framed .elementor-icon, .elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-default .elementor-icon{color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-framed .elementor-icon, .elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-default .elementor-icon svg{fill:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-b217cb3{text-align:center;margin:05px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;}.elementor-9323 .elementor-element.elementor-element-b217cb3 .elementor-heading-title{font-family:\"Rubik\", Sans-serif;font-size:16px;font-weight:bold;text-transform:uppercase;line-height:1em;color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-c39e954{text-align:center;color:var( --e-global-color-text );font-family:\"Rubik\", Sans-serif;font-size:14px;font-weight:300;line-height:1.2em;margin:5px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;}.elementor-9323 .elementor-element.elementor-element-7143336{text-align:center;font-size:14px;}@media(max-width:1024px){.elementor-9323 .elementor-element.elementor-element-c39e954{line-height:1.5em;}}@media(min-width:768px){.elementor-9323 .elementor-element.elementor-element-ef506d7{--content-width:100%;}}@media(max-width:767px){.elementor-9323 .elementor-element.elementor-element-c39e954{font-size:16px;line-height:1.3em;}}\/* Start custom CSS for container, class: .elementor-element-ef506d7 *\/.elementor-9323 .elementor-element.elementor-element-ef506d7{\n    max-width: 400px;\n}\/* End custom CSS *\/<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"9323\" class=\"elementor elementor-9323 dce-elementor-rendering-id-9 e-loop-item e-loop-item-9332 post-9332 certification type-certification status-publish hentry certification-category-documentation\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a data-dce-background-color=\"#63AADC17\" data-dce-background-hover-color=\"#63AADC30\" class=\"elementor-element elementor-element-ef506d7 e-flex e-con-boxed e-con e-parent\" data-id=\"ef506d7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/www.eurosets.com\/wp-content\/uploads\/2026\/02\/Politica-PDG.pdf\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-affdc25 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"affdc25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-file-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288 248v28c0 6.6-5.4 12-12 12H108c-6.6 0-12-5.4-12-12v-28c0-6.6 5.4-12 12-12h168c6.6 0 12 5.4 12 12zm-12 72H108c-6.6 0-12 5.4-12 12v28c0 6.6 5.4 12 12 12h168c6.6 0 12-5.4 12-12v-28c0-6.6-5.4-12-12-12zm108-188.1V464c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V48C0 21.5 21.5 0 48 0h204.1C264.8 0 277 5.1 286 14.1L369.9 98c9 8.9 14.1 21.2 14.1 33.9zm-128-80V128h76.1L256 51.9zM336 464V176H232c-13.3 0-24-10.7-24-24V48H48v416h288z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-title-color=\"#003D6B\" class=\"elementor-element elementor-element-b217cb3 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"b217cb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">UNI\/PdR 125:2022 Policy<\/h4>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-9944 certification type-certification status-publish hentry certification-category-documentation dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"9944\" data-dce-post-index=\"9\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<style>.elementor-9323 .elementor-element.elementor-element-ef506d7{--display:flex;--flex-direction:column;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:flex-start;--align-items:center;--background-transition:0.3s;--border-radius:20px 20px 20px 20px;--margin-top:10px;--margin-bottom:10px;--margin-left:10px;--margin-right:10px;--padding-top:20px;--padding-bottom:20px;--padding-left:20px;--padding-right:20px;}.elementor-9323 .elementor-element.elementor-element-ef506d7:not(.elementor-motion-effects-element-type-background), .elementor-9323 .elementor-element.elementor-element-ef506d7 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#63AADC17;}.elementor-9323 .elementor-element.elementor-element-ef506d7:hover{background-color:#63AADC30;}.elementor-9323 .elementor-element.elementor-element-affdc25 .elementor-icon-wrapper{text-align:center;}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-stacked .elementor-icon{background-color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-framed .elementor-icon, .elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-default .elementor-icon{color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-framed .elementor-icon, .elementor-9323 .elementor-element.elementor-element-affdc25.elementor-view-default .elementor-icon svg{fill:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-b217cb3{text-align:center;margin:05px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;}.elementor-9323 .elementor-element.elementor-element-b217cb3 .elementor-heading-title{font-family:\"Rubik\", Sans-serif;font-size:16px;font-weight:bold;text-transform:uppercase;line-height:1em;color:var( --e-global-color-primary );}.elementor-9323 .elementor-element.elementor-element-c39e954{text-align:center;color:var( --e-global-color-text );font-family:\"Rubik\", Sans-serif;font-size:14px;font-weight:300;line-height:1.2em;margin:5px 0px calc(var(--kit-widget-spacing, 0px) + 0px) 0px;}.elementor-9323 .elementor-element.elementor-element-7143336{text-align:center;font-size:14px;}@media(max-width:1024px){.elementor-9323 .elementor-element.elementor-element-c39e954{line-height:1.5em;}}@media(min-width:768px){.elementor-9323 .elementor-element.elementor-element-ef506d7{--content-width:100%;}}@media(max-width:767px){.elementor-9323 .elementor-element.elementor-element-c39e954{font-size:16px;line-height:1.3em;}}\/* Start custom CSS for container, class: .elementor-element-ef506d7 *\/.elementor-9323 .elementor-element.elementor-element-ef506d7{\n    max-width: 400px;\n}\/* End custom CSS *\/<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"9323\" class=\"elementor elementor-9323 dce-elementor-rendering-id-10 e-loop-item e-loop-item-9944 post-9944 certification type-certification status-publish hentry certification-category-documentation\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<a data-dce-background-color=\"#63AADC17\" data-dce-background-hover-color=\"#63AADC30\" class=\"elementor-element elementor-element-ef506d7 e-flex e-con-boxed e-con e-parent\" data-id=\"ef506d7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"https:\/\/www.eurosets.com\/wp-content\/uploads\/2025\/10\/Procedura-Whistleblowing-Eurosets-1-ENG.pdf\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-affdc25 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"affdc25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-file-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288 248v28c0 6.6-5.4 12-12 12H108c-6.6 0-12-5.4-12-12v-28c0-6.6 5.4-12 12-12h168c6.6 0 12 5.4 12 12zm-12 72H108c-6.6 0-12 5.4-12 12v28c0 6.6 5.4 12 12 12h168c6.6 0 12-5.4 12-12v-28c0-6.6-5.4-12-12-12zm108-188.1V464c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V48C0 21.5 21.5 0 48 0h204.1C264.8 0 277 5.1 286 14.1L369.9 98c9 8.9 14.1 21.2 14.1 33.9zm-128-80V128h76.1L256 51.9zM336 464V176H232c-13.3 0-24-10.7-24-24V48H48v416h288z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-title-color=\"#003D6B\" class=\"elementor-element elementor-element-b217cb3 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"b217cb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Whistleblowing Procedure<\/h4>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<!-- dce invisible element 98d0467 -->\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>DOCUMENTATION Welcome to the Eurosets Documentation area. We are committed to supporting healthcare professionals by providing easy access to the latest technical and clinical information regarding our life-saving portfolio. Eurosets&#8217; book for celebrating 30 years Whistleblowing procedure<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"slim_seo":{"title":"Documentation - Eurosets","description":"DOCUMENTATION Welcome to the Eurosets Documentation area. We are committed to supporting healthcare professionals by providing easy access to the latest technic"},"footnotes":""},"class_list":["post-9309","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.eurosets.com\/it\/wp-json\/wp\/v2\/pages\/9309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eurosets.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.eurosets.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.eurosets.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eurosets.com\/it\/wp-json\/wp\/v2\/comments?post=9309"}],"version-history":[{"count":97,"href":"https:\/\/www.eurosets.com\/it\/wp-json\/wp\/v2\/pages\/9309\/revisions"}],"predecessor-version":[{"id":9950,"href":"https:\/\/www.eurosets.com\/it\/wp-json\/wp\/v2\/pages\/9309\/revisions\/9950"}],"wp:attachment":[{"href":"https:\/\/www.eurosets.com\/it\/wp-json\/wp\/v2\/media?parent=9309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}